{"id":248,"count":5,"description":"","link":"https:\/\/denox.eu\/fr\/categoria-producto\/nettoyage\/nettoyage-professionnel\/","name":"Nettoyage professionnel","slug":"nettoyage-professionnel","taxonomy":"product_cat","parent":247,"meta":[],"_links":{"self":[{"href":"https:\/\/denox.eu\/fr\/wp-json\/wp\/v2\/product_cat\/248"}],"collection":[{"href":"https:\/\/denox.eu\/fr\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/denox.eu\/fr\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/denox.eu\/fr\/wp-json\/wp\/v2\/product_cat\/247"}],"wp:post_type":[{"href":"https:\/\/denox.eu\/fr\/wp-json\/wp\/v2\/product?product_cat=248"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}