{"id":4880,"date":"2020-12-14T09:20:07","date_gmt":"2020-12-14T08:20:07","guid":{"rendered":"https:\/\/denox.eu\/producto\/seau-selecta-12-l\/"},"modified":"2021-04-22T08:26:00","modified_gmt":"2021-04-22T06:26:00","slug":"seau-selecta-12l","status":"publish","type":"product","link":"https:\/\/denox.eu\/fr\/producto\/seau-selecta-12l\/","title":{"rendered":"Seau Selecta 12 L."},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p class=\"prod-desc-resaltado\">Dimensions (mm): \u00d8 325 x 270<\/p>\n<p class=\"prod-desc-unidades\"><img decoding=\"async\" class=\"prod-desc-icon\" role=\"img\" src=\"\/wp-content\/uploads\/icon-box-cont.svg\" \/> 12<\/p>\n<p class=\"prod-desc-unidades\"><img decoding=\"async\" class=\"prod-desc-icon\" role=\"img\" src=\"\/wp-content\/uploads\/icon-pallet-box.svg\" \/> 432 u.<\/p>\n<p><img decoding=\"async\" class=\"prod-carac-icon\" src=\"\/wp-content\/uploads\/icon-prod-color-azul-claro.svg\" \/><img decoding=\"async\" class=\"prod-carac-icon\" src=\"\/wp-content\/uploads\/icon-prod-color-gris.svg\" \/><img decoding=\"async\" class=\"prod-carac-icon\" src=\"\/wp-content\/uploads\/icon-prod-carac-alimentacion.svg\" \/><\/p>\n","protected":false},"featured_media":5910,"template":"","meta":[],"product_cat":[247,249],"product_tag":[],"_links":{"self":[{"href":"https:\/\/denox.eu\/fr\/wp-json\/wp\/v2\/product\/4880"}],"collection":[{"href":"https:\/\/denox.eu\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/denox.eu\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/denox.eu\/fr\/wp-json\/wp\/v2\/media\/5910"}],"wp:attachment":[{"href":"https:\/\/denox.eu\/fr\/wp-json\/wp\/v2\/media?parent=4880"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/denox.eu\/fr\/wp-json\/wp\/v2\/product_cat?post=4880"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/denox.eu\/fr\/wp-json\/wp\/v2\/product_tag?post=4880"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}