{"id":4876,"date":"2020-12-14T09:20:07","date_gmt":"2020-12-14T08:20:07","guid":{"rendered":"https:\/\/denox.eu\/producto\/seau-espagnol-oval-14-l\/"},"modified":"2021-04-22T08:28:39","modified_gmt":"2021-04-22T06:28:39","slug":"seau-espagnol-oval-14l","status":"publish","type":"product","link":"https:\/\/denox.eu\/fr\/producto\/seau-espagnol-oval-14l\/","title":{"rendered":"Seau espagnol Oval 14 L."},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<ul>\n<li>Nouvelle conception d&rsquo;\u00e9gouttoir de grande capacit\u00e9.<\/li>\n<\/ul>\n<p class=\"prod-desc-resaltado\">Dimensions (mm): 400 x 285 x 290<\/p>\n<p class=\"prod-desc-unidades\"><img decoding=\"async\" class=\"prod-desc-icon\" role=\"img\" src=\"\/wp-content\/uploads\/icon-box-cont.svg\" \/> 8<\/p>\n<p class=\"prod-desc-unidades\"><img decoding=\"async\" class=\"prod-desc-icon\" role=\"img\" src=\"\/wp-content\/uploads\/icon-pallet-box.svg\" \/> 160 u.<\/p>\n<p><img decoding=\"async\" class=\"prod-carac-icon\" src=\"\/wp-content\/uploads\/icon-prod-color-azul.svg\" \/><img decoding=\"async\" class=\"prod-carac-icon\" src=\"\/wp-content\/uploads\/icon-prod-color-verde.svg\" \/><img decoding=\"async\" class=\"prod-carac-icon\" src=\"\/wp-content\/uploads\/icon-prod-color-rojo.svg\" \/><img decoding=\"async\" class=\"prod-carac-icon\" src=\"\/wp-content\/uploads\/icon-prod-color-amarillo.svg\" \/><img decoding=\"async\" class=\"prod-carac-icon\" src=\"\/wp-content\/uploads\/icon-prod-color-gris.svg\" \/><\/p>\n","protected":false},"featured_media":5898,"template":"","meta":[],"product_cat":[247,249],"product_tag":[],"_links":{"self":[{"href":"https:\/\/denox.eu\/fr\/wp-json\/wp\/v2\/product\/4876"}],"collection":[{"href":"https:\/\/denox.eu\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/denox.eu\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/denox.eu\/fr\/wp-json\/wp\/v2\/media\/5898"}],"wp:attachment":[{"href":"https:\/\/denox.eu\/fr\/wp-json\/wp\/v2\/media?parent=4876"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/denox.eu\/fr\/wp-json\/wp\/v2\/product_cat?post=4876"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/denox.eu\/fr\/wp-json\/wp\/v2\/product_tag?post=4876"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}