{"id":4611,"date":"2020-12-14T09:16:21","date_gmt":"2020-12-14T08:16:21","guid":{"rendered":"https:\/\/denox.eu\/producto\/gastronox-1-4-h65\/"},"modified":"2021-10-21T17:07:25","modified_gmt":"2021-10-21T15:07:25","slug":"gastronox-1-4-h65-fr","status":"publish","type":"product","link":"https:\/\/denox.eu\/fr\/producto\/gastronox-1-4-h65-fr\/","title":{"rendered":"Gastronox 1\/4 H65"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<h2>Bo\u00eete herm\u00e9tique Gastronorm 1\/4 H65<\/h2>\n<ul>\n<li>Bo\u00eete herm\u00e9tique professionnel avec couvercle \u00e0 double verrouillage et ouverture facile au niveau des coins.<\/li>\n<li>Sans bisph\u00e9nol. Qualit\u00e9 alimentaire conforme aux normes internationales, v\u00e9rifi\u00e9e avec des essais de migration.<\/li>\n<li>\u00c9tiquette de tra\u00e7abilit\u00e9 int\u00e9gr\u00e9e.<\/li>\n<li>Clip color\u00e9 pour l&rsquo;identification des aliments.<\/li>\n<li>Robustesse et r\u00e9sistance \u00e0 la fatigue \u00e9prouv\u00e9es.<\/li>\n<\/ul>\n<p class=\"prod-desc-resaltado\">Dimensions (mm): 265 x 162 x 65<br \/>\nCapacit\u00e9: 1,8L.<\/p>\n<p class=\"prod-desc-unidades\"><img decoding=\"async\" class=\"prod-desc-icon\" role=\"img\" src=\"\/wp-content\/uploads\/icon-box-cont.svg\" \/> 6<\/p>\n<p class=\"prod-desc-unidades\"><img decoding=\"async\" class=\"prod-desc-icon\" role=\"img\" src=\"\/wp-content\/uploads\/icon-pallet-box.svg\" \/> 720 u.<\/p>\n<p><img decoding=\"async\" class=\"prod-carac-icon\" src=\"\/wp-content\/uploads\/icon-prod-carac-gastronox.png\" \/><img decoding=\"async\" class=\"prod-carac-icon\" src=\"\/wp-content\/uploads\/icon-prod-carac-microondas.svg\" \/><img decoding=\"async\" class=\"prod-carac-icon\" src=\"\/wp-content\/uploads\/icon-prod-carac-lavavajillas.svg\" \/><img decoding=\"async\" class=\"prod-carac-icon\" src=\"\/wp-content\/uploads\/icon-prod-carac-alimentacion.svg\" \/><img decoding=\"async\" class=\"prod-carac-icon\" src=\"\/wp-content\/uploads\/icon-prod-carac-caja-encajable.svg\" \/><img decoding=\"async\" class=\"prod-carac-icon\" src=\"\/wp-content\/uploads\/icon-prod-carac-bpa.svg\" \/><\/p>\n","protected":false},"featured_media":5474,"template":"","meta":[],"product_cat":[232,233,234],"product_tag":[],"_links":{"self":[{"href":"https:\/\/denox.eu\/fr\/wp-json\/wp\/v2\/product\/4611"}],"collection":[{"href":"https:\/\/denox.eu\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/denox.eu\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/denox.eu\/fr\/wp-json\/wp\/v2\/media\/5474"}],"wp:attachment":[{"href":"https:\/\/denox.eu\/fr\/wp-json\/wp\/v2\/media?parent=4611"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/denox.eu\/fr\/wp-json\/wp\/v2\/product_cat?post=4611"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/denox.eu\/fr\/wp-json\/wp\/v2\/product_tag?post=4611"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}