{"id":7177,"date":"2025-01-13T09:27:55","date_gmt":"2025-01-13T08:27:55","guid":{"rendered":"https:\/\/denox.eu\/denox-exposera-ses-produits-au-sirha-2025-salon-de-reference-de-la-filiere-horeca\/"},"modified":"2025-01-14T13:58:16","modified_gmt":"2025-01-14T12:58:16","slug":"denox-exposera-ses-produits-au-sirha-2025-salon-de-reference-de-la-filiere-horeca","status":"publish","type":"post","link":"https:\/\/denox.eu\/fr\/denox-exposera-ses-produits-au-sirha-2025-salon-de-reference-de-la-filiere-horeca\/","title":{"rendered":"Denox exposera ses produits au Sirha 2025, salon de r\u00e9f\u00e9rence de la fili\u00e8re HORECA."},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"background-color: rgba(255,255,255,0);background-position: center center;background-repeat: no-repeat;border-width: 0px 0px 0px 0px;border-color:#e2e2e2;border-style:solid;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start\" style=\"max-width:1185.6px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\" style=\"background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;padding: 0px 0px 0px 0px;\"><style type=\"text\/css\">@media only screen and (max-width:1024px) {.fusion-title.fusion-title-1{margin-top:10px!important;margin-bottom:15px!important;}}@media only screen and (max-width:640px) {.fusion-title.fusion-title-1{margin-top:10px!important;margin-bottom:10px!important;}}<\/style><div class=\"fusion-title title fusion-title-1 fusion-sep-none fusion-title-text fusion-title-size-one\" style=\"margin-top:10px;margin-bottom:15px;\"><h1 class=\"title-heading-left\" style=\"margin:0;\">Du 23 au 27 janvier, Denox fera la promotion de sa large gamme de produits destin\u00e9s \u00e0 l&rsquo;h\u00f4tellerie dans cette importante vitrine internationale \u00e0 Lyon, en France.<\/h1><\/div><div class=\"fusion-text fusion-text-1\"><p>Dans cette \u00e9dition, le stand Denox pr\u00e9sentera au march\u00e9 fran\u00e7ais ses produits avec le plus de succ\u00e8s du canal HORECA, dans l&rsquo;un des \u00e9v\u00e9nements les plus importants de la restauration et de l&rsquo;h\u00f4tellerie au monde en France.<br \/>\nLe salon rassemblera plus de 4 000 exposants et marques de plus de 40 pays au palais des congr\u00e8s de la ville fran\u00e7aise, <strong>Eurexpo Lyon<\/strong>. Les principaux fournisseurs et fabricants d&rsquo;aliments et de boissons du monde entier participent \u00e0 ce salon, qui propose une grande vari\u00e9t\u00e9 de produits et services li\u00e9s \u00e0 l&rsquo;industrie alimentaire.<\/p>\n<\/div><div style=\"text-align:center;\"><span class=\" fusion-imageframe imageframe-none imageframe-1 hover-type-none\" style=\"margin-bottom:20px;\"><img decoding=\"async\" width=\"850\" height=\"315\" title=\"SOCIAL_MEDIA_BANNER_6A114_1380\" src=\"https:\/\/denox.eu\/wp-content\/uploads\/SOCIAL_MEDIA_BANNER_6A114_1380.jpg\" data-orig-src=\"https:\/\/denox.eu\/wp-content\/uploads\/SOCIAL_MEDIA_BANNER_6A114_1380.jpg\" class=\"lazyload img-responsive wp-image-7170\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27850%27%20height%3D%27315%27%20viewBox%3D%270%200%20850%20315%27%3E%3Crect%20width%3D%27850%27%20height%3D%273315%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/denox.eu\/wp-content\/uploads\/SOCIAL_MEDIA_BANNER_6A114_1380-200x74.jpg 200w, https:\/\/denox.eu\/wp-content\/uploads\/SOCIAL_MEDIA_BANNER_6A114_1380-400x148.jpg 400w, https:\/\/denox.eu\/wp-content\/uploads\/SOCIAL_MEDIA_BANNER_6A114_1380-600x222.jpg 600w, https:\/\/denox.eu\/wp-content\/uploads\/SOCIAL_MEDIA_BANNER_6A114_1380-800x296.jpg 800w, https:\/\/denox.eu\/wp-content\/uploads\/SOCIAL_MEDIA_BANNER_6A114_1380.jpg 850w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 1024px) 100vw, (max-width: 640px) 100vw, 850px\" \/><\/span><\/div><div class=\"fusion-text fusion-text-2\"><p>Le Stand Denox sera situ\u00e9 dans le <strong>pavillon 6, stand A114<\/strong> et pr\u00e9sentera une s\u00e9lection de produits avec les principales r\u00e9f\u00e9rences de la marque, ainsi que les derni\u00e8res nouveaut\u00e9s.<br \/>\nApr\u00e8s une ann\u00e9e de forte croissance pour l&rsquo;entreprise, Denox se consolide sur le <strong>march\u00e9 \u00e9tranger<\/strong> comme l&rsquo;un des principaux fournisseurs de solutions pour cuisines professionnelles en Europe.<br \/>\nPendant le salon, vous pourrez voir l&rsquo;un de leurs derniers d\u00e9veloppements. Il s&rsquo;agit de la large gamme de Plateaux Fast Food, compos\u00e9e de 4 tailles et disponible en 5 couleurs : bleu, vert, rouge, marron et noir. Tous les mod\u00e8les sont personnalisables et s\u2019adaptent donc aux besoins de n\u2019importe quel \u00e9tablissement.<br \/>\nDe plus, sur le stand Denox, vous pourrez voir ses principaux produits, parmi lesquels une gamme compl\u00e8te de <strong>conteneurs et seaux<\/strong> pour le tri des d\u00e9chets, la gamme \u00e0 succ\u00e8s de produits <strong>Gastronox <\/strong>compos\u00e9e de conteneurs pour le stockage et la conservation des aliments dans les cuisines professionnelles, la grande famille de <strong>bo\u00eetes industrielles<\/strong>, r\u00e9sistantes et adapt\u00e9es \u00e0 un usage alimentaire et sa vaste collection de <strong>produits d&rsquo;ustensiles de cuisine pour la cuisine professionnelle.<\/strong><\/p>\n<p>Pour tous ceux qui souhaitent conna\u00eetre le catalogue complet Denox, vous pourrez vous rendre au <strong>Pavillon 6 Stand A114 au Sirha 2025, du 23 au 27 janvier<\/strong>.<\/p>\n<p>Vous ne pouvez pas manquer le rendez-vous!<\/p>\n<\/div><\/div><\/div><style type=\"text\/css\">.fusion-body .fusion-builder-column-0{width:100% !important;margin-top : 0px;margin-bottom : 20px;}.fusion-builder-column-0 > .fusion-column-wrapper {padding-top : 0px !important;padding-right : 0px !important;margin-right : 1.92%;padding-bottom : 0px !important;padding-left : 0px !important;margin-left : 1.92%;}@media only screen and (max-width:1024px) {.fusion-body .fusion-builder-column-0{width:100% !important;order : 0;}.fusion-builder-column-0 > .fusion-column-wrapper {margin-right : 1.92%;margin-left : 1.92%;}}@media only screen and (max-width:640px) {.fusion-body .fusion-builder-column-0{width:100% !important;order : 0;}.fusion-builder-column-0 > .fusion-column-wrapper {margin-right : 1.92%;margin-left : 1.92%;}}<\/style><\/div><style type=\"text\/css\">.fusion-body .fusion-flex-container.fusion-builder-row-1{ padding-top : 0px;margin-top : 0px;padding-right : 0px;padding-bottom : 0px;margin-bottom : 0px;padding-left : 0px;}<\/style><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":6,"featured_media":7170,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[204],"tags":[],"_links":{"self":[{"href":"https:\/\/denox.eu\/fr\/wp-json\/wp\/v2\/posts\/7177"}],"collection":[{"href":"https:\/\/denox.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/denox.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/denox.eu\/fr\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/denox.eu\/fr\/wp-json\/wp\/v2\/comments?post=7177"}],"version-history":[{"count":1,"href":"https:\/\/denox.eu\/fr\/wp-json\/wp\/v2\/posts\/7177\/revisions"}],"predecessor-version":[{"id":7180,"href":"https:\/\/denox.eu\/fr\/wp-json\/wp\/v2\/posts\/7177\/revisions\/7180"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/denox.eu\/fr\/wp-json\/wp\/v2\/media\/7170"}],"wp:attachment":[{"href":"https:\/\/denox.eu\/fr\/wp-json\/wp\/v2\/media?parent=7177"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/denox.eu\/fr\/wp-json\/wp\/v2\/categories?post=7177"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/denox.eu\/fr\/wp-json\/wp\/v2\/tags?post=7177"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}