{"id":6943,"date":"2023-04-28T09:56:54","date_gmt":"2023-04-28T07:56:54","guid":{"rendered":"https:\/\/denox.eu\/?post_type=product&#038;p=6943"},"modified":"2023-04-28T11:56:00","modified_gmt":"2023-04-28T09:56:00","slug":"tray-gn-1-1-h100","status":"publish","type":"product","link":"https:\/\/denox.eu\/en\/producto\/tray-gn-1-1-h100\/","title":{"rendered":"TRAY GN 1\/1 H100"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<ul>\n<li>Gatronorm melamine tray with an aesthetic gloss finish.<\/li>\n<li>Special for food presentation.<\/li>\n<li>Melamine provides greater durability due to its greater impact resistance and lower weight.<\/li>\n<li>Dishwasher safe.<\/li>\n<\/ul>\n<p class=\"prod-desc-resaltado\">Sizing (mm) : 530 x 325 x 100<\/p>\n<p class=\"prod-desc-unidades\"><img decoding=\"async\" class=\"prod-desc-icon\" role=\"img\" src=\"\/wp-content\/uploads\/icon-box-cont.svg\">  6<\/p>\n<p class=\"prod-desc-unidades\"><img decoding=\"async\" class=\"prod-desc-icon\" role=\"img\" src=\"\/wp-content\/uploads\/icon-pallet-box.svg\"> 420 units<\/p>\n<p><img decoding=\"async\" class=\"prod-carac-icon\" src=\"\/wp-content\/uploads\/icon-prod-carac-alimentacion.svg\"><img decoding=\"async\" class=\"prod-carac-icon\" src=\"\/wp-content\/uploads\/icon-prod-carac-lavavajillas.svg\"><img decoding=\"async\" class=\"prod-carac-icon\" src=\"\/wp-content\/uploads\/icon-prod-carac-caja-encajable.svg\"><\/p>\n","protected":false},"featured_media":6910,"template":"","meta":[],"product_cat":[208,107,132],"product_tag":[],"_links":{"self":[{"href":"https:\/\/denox.eu\/en\/wp-json\/wp\/v2\/product\/6943"}],"collection":[{"href":"https:\/\/denox.eu\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/denox.eu\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/denox.eu\/en\/wp-json\/wp\/v2\/media\/6910"}],"wp:attachment":[{"href":"https:\/\/denox.eu\/en\/wp-json\/wp\/v2\/media?parent=6943"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/denox.eu\/en\/wp-json\/wp\/v2\/product_cat?post=6943"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/denox.eu\/en\/wp-json\/wp\/v2\/product_tag?post=6943"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}