{"id":3721,"date":"2020-12-14T09:19:23","date_gmt":"2020-12-14T08:19:23","guid":{"rendered":"https:\/\/denox.eu\/producto\/tray-europa-14-l\/"},"modified":"2020-12-09T09:29:13","modified_gmt":"2020-12-09T09:29:13","slug":"tray-europa-14-l","status":"publish","type":"product","link":"https:\/\/denox.eu\/en\/producto\/tray-europa-14-l\/","title":{"rendered":"Tray Europa 14 L."},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p class=\"prod-desc-resaltado\">Sizing (mm) : 410 x 290 x 145<\/p>\n<p class=\"prod-desc-unidades\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/icon-box-cont.svg\" class=\"prod-desc-icon\"  role=\"img\" \/> 6<\/p>\n<p class=\"prod-desc-unidades\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/icon-pallet-box.svg\" class=\"prod-desc-icon\"  role=\"img\" \/> 128 units<\/p>\n","protected":false},"featured_media":5788,"template":"","meta":[],"product_cat":[129,143],"product_tag":[],"_links":{"self":[{"href":"https:\/\/denox.eu\/en\/wp-json\/wp\/v2\/product\/3721"}],"collection":[{"href":"https:\/\/denox.eu\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/denox.eu\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/denox.eu\/en\/wp-json\/wp\/v2\/media\/5788"}],"wp:attachment":[{"href":"https:\/\/denox.eu\/en\/wp-json\/wp\/v2\/media?parent=3721"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/denox.eu\/en\/wp-json\/wp\/v2\/product_cat?post=3721"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/denox.eu\/en\/wp-json\/wp\/v2\/product_tag?post=3721"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}