{"id":3682,"date":"2020-12-14T09:19:06","date_gmt":"2020-12-14T08:19:06","guid":{"rendered":"https:\/\/denox.eu\/producto\/medium-bowl\/"},"modified":"2020-12-09T09:29:28","modified_gmt":"2020-12-09T09:29:28","slug":"medium-bowl","status":"publish","type":"product","link":"https:\/\/denox.eu\/en\/producto\/medium-bowl\/","title":{"rendered":"Medium bowl"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p class=\"prod-desc-resaltado\">Sizing (mm) : \u00d8 240 x 95<\/p>\n<p class=\"prod-desc-unidades\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/icon-box-cont.svg\" class=\"prod-desc-icon\"  role=\"img\" \/> 6<\/p>\n<p class=\"prod-desc-unidades\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/icon-pallet-box.svg\" class=\"prod-desc-icon\"  role=\"img\" \/> 540 units<\/p>\n<p><img decoding=\"async\" src=\"\/wp-content\/uploads\/icon-prod-color-blanco.svg\" class=\"prod-carac-icon\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/icon-prod-color-verde.svg\" class=\"prod-carac-icon\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/icon-prod-carac-alimentacion.svg\" class=\"prod-carac-icon\"><\/p>\n","protected":false},"featured_media":5631,"template":"","meta":[],"product_cat":[105,106],"product_tag":[],"_links":{"self":[{"href":"https:\/\/denox.eu\/en\/wp-json\/wp\/v2\/product\/3682"}],"collection":[{"href":"https:\/\/denox.eu\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/denox.eu\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/denox.eu\/en\/wp-json\/wp\/v2\/media\/5631"}],"wp:attachment":[{"href":"https:\/\/denox.eu\/en\/wp-json\/wp\/v2\/media?parent=3682"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/denox.eu\/en\/wp-json\/wp\/v2\/product_cat?post=3682"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/denox.eu\/en\/wp-json\/wp\/v2\/product_tag?post=3682"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}