{"id":3621,"date":"2020-12-14T09:17:54","date_gmt":"2020-12-14T08:17:54","guid":{"rendered":"https:\/\/denox.eu\/producto\/9-feet-palet\/"},"modified":"2020-12-09T09:30:11","modified_gmt":"2020-12-09T09:30:11","slug":"9-feet-palet","status":"publish","type":"product","link":"https:\/\/denox.eu\/en\/producto\/9-feet-palet\/","title":{"rendered":"9 feet palet"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p class=\"prod-desc-resaltado\">\n<ul>\n<li>Pallets suitable for pest control.<\/li>\n<li>Prevents pollution.<\/li>\n<li>Resistant to unfavourable weather conditions.<\/li>\n<li>9 feet. <\/li>\n<li>Food use.<\/li>\n<li>Static load capacity: 1800 Kg.<\/li>\n<li>Dynamic load capacity: 600 Kg.<\/li>\n<\/ul>\n<p class=\"prod-desc-resaltado\">Sizing (mm) : 800 x 1200<\/p>\n<p class=\"prod-desc-unidades\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/icon-box-cont.svg\" class=\"prod-desc-icon\"  role=\"img\" \/> 1<\/p>\n<p class=\"prod-desc-unidades\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/icon-pallet-box.svg\" class=\"prod-desc-icon\"  role=\"img\" \/> 15 units<\/p>\n<p class=\"prod-desc-unidades\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/icon-peso.svg\" class=\"prod-desc-icon\"  role=\"img\" \/> 7<\/p>\n<p><img decoding=\"async\" src=\"\/wp-content\/uploads\/icon-prod-color-blanco.svg\" class=\"prod-carac-icon\"><\/p>\n","protected":false},"featured_media":6075,"template":"","meta":[],"product_cat":[144,146],"product_tag":[],"_links":{"self":[{"href":"https:\/\/denox.eu\/en\/wp-json\/wp\/v2\/product\/3621"}],"collection":[{"href":"https:\/\/denox.eu\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/denox.eu\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/denox.eu\/en\/wp-json\/wp\/v2\/media\/6075"}],"wp:attachment":[{"href":"https:\/\/denox.eu\/en\/wp-json\/wp\/v2\/media?parent=3621"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/denox.eu\/en\/wp-json\/wp\/v2\/product_cat?post=3621"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/denox.eu\/en\/wp-json\/wp\/v2\/product_tag?post=3621"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}