{"id":3615,"date":"2020-12-14T09:17:54","date_gmt":"2020-12-14T08:17:54","guid":{"rendered":"https:\/\/denox.eu\/producto\/foldable-crate-es-4317\/"},"modified":"2023-12-14T11:12:17","modified_gmt":"2023-12-14T10:12:17","slug":"foldable-crate-es-4317","status":"publish","type":"product","link":"https:\/\/denox.eu\/en\/producto\/foldable-crate-es-4317\/","title":{"rendered":"Foldable EN 4317 crate"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p class=\"prod-desc-resaltado\">Sizing (mm) : 400 x 300 x 174<\/p>\n<p class=\"prod-desc-unidades\"><img decoding=\"async\" class=\"prod-desc-icon\" role=\"img\" src=\"\/wp-content\/uploads\/icon-box-cont.svg\" \/> 1<\/p>\n<p class=\"prod-desc-unidades\"><img decoding=\"async\" class=\"prod-desc-icon\" role=\"img\" src=\"\/wp-content\/uploads\/icon-pallet-box.svg\" \/> 624 units<\/p>\n<p><img decoding=\"async\" class=\"prod-carac-icon\" src=\"\/wp-content\/uploads\/icon-prod-color-gris.svg\" \/><img decoding=\"async\" class=\"prod-carac-icon\" src=\"\/wp-content\/uploads\/icon-prod-capnobag-17.svg\" \/><img decoding=\"async\" class=\"prod-carac-icon\" src=\"\/wp-content\/uploads\/icon-prod-carac-alimentacion.svg\" \/><img decoding=\"async\" class=\"prod-carac-icon\" src=\"\/wp-content\/uploads\/icon-prod-carac-caja-apilable.svg\" \/><\/p>\n","protected":false},"featured_media":4189,"template":"","meta":[],"product_cat":[98,104],"product_tag":[],"_links":{"self":[{"href":"https:\/\/denox.eu\/en\/wp-json\/wp\/v2\/product\/3615"}],"collection":[{"href":"https:\/\/denox.eu\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/denox.eu\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/denox.eu\/en\/wp-json\/wp\/v2\/media\/4189"}],"wp:attachment":[{"href":"https:\/\/denox.eu\/en\/wp-json\/wp\/v2\/media?parent=3615"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/denox.eu\/en\/wp-json\/wp\/v2\/product_cat?post=3615"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/denox.eu\/en\/wp-json\/wp\/v2\/product_tag?post=3615"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}