{"id":3611,"date":"2020-12-14T09:17:54","date_gmt":"2020-12-14T08:17:54","guid":{"rendered":"https:\/\/denox.eu\/producto\/open-dolly\/"},"modified":"2025-02-17T09:14:34","modified_gmt":"2025-02-17T08:14:34","slug":"open-dolly","status":"publish","type":"product","link":"https:\/\/denox.eu\/en\/producto\/open-dolly\/","title":{"rendered":"EU Open dolly"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<ul>\n<li>4 wheels with a 75 mm diameter, silent (made of rubber) and steerable.<\/li>\n<li>Improved ergonomics with clefts that make it easier to lift boxes without handles.<\/li>\n<\/ul>\n<p class=\"prod-desc-resaltado\">Sizing (mm) : 600 x 400<\/p>\n<p class=\"prod-desc-unidades\"><img decoding=\"async\" class=\"prod-desc-icon\" role=\"img\" src=\"\/wp-content\/uploads\/icon-box-cont.svg\" \/> 1<\/p>\n<p class=\"prod-desc-unidades\"><img decoding=\"async\" class=\"prod-desc-icon\" role=\"img\" src=\"\/wp-content\/uploads\/icon-pallet-box.svg\" \/> 34 units<\/p>\n<p class=\"prod-desc-unidades\"><img decoding=\"async\" class=\"prod-desc-icon\" role=\"img\" src=\"\/wp-content\/uploads\/icon-peso-sop.svg\" \/> 100<\/p>\n<p><img decoding=\"async\" class=\"prod-carac-icon\" src=\"\/wp-content\/uploads\/icon-prod-color-negro.svg\" \/><\/p>\n","protected":false},"featured_media":3928,"template":"","meta":[],"product_cat":[98,100],"product_tag":[],"_links":{"self":[{"href":"https:\/\/denox.eu\/en\/wp-json\/wp\/v2\/product\/3611"}],"collection":[{"href":"https:\/\/denox.eu\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/denox.eu\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/denox.eu\/en\/wp-json\/wp\/v2\/media\/3928"}],"wp:attachment":[{"href":"https:\/\/denox.eu\/en\/wp-json\/wp\/v2\/media?parent=3611"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/denox.eu\/en\/wp-json\/wp\/v2\/product_cat?post=3611"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/denox.eu\/en\/wp-json\/wp\/v2\/product_tag?post=3611"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}