{"id":3610,"date":"2020-12-14T09:17:54","date_gmt":"2020-12-14T08:17:54","guid":{"rendered":"https:\/\/denox.eu\/producto\/lid-es64\/"},"modified":"2025-02-21T09:49:29","modified_gmt":"2025-02-21T08:49:29","slug":"lid-es64","status":"publish","type":"product","link":"https:\/\/denox.eu\/en\/producto\/lid-es64\/","title":{"rendered":"EU 64 lid"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<ul>\n<li>Holes that allow strapping the lid to the box.<\/li>\n<li>Clefts for easy side opening.<\/li>\n<li>Resistant to temperatures ranging between -40\u00ba and +75\u00ba.<\/li>\n<\/ul>\n<p class=\"prod-desc-resaltado\">Sizing (mm) : 600 x 400 x 25<\/p>\n<p class=\"prod-desc-unidades\"><img decoding=\"async\" class=\"prod-desc-icon\" role=\"img\" src=\"\/wp-content\/uploads\/icon-box-cont.svg\" \/> 1<\/p>\n<p class=\"prod-desc-unidades\"><img decoding=\"async\" class=\"prod-desc-icon\" role=\"img\" src=\"\/wp-content\/uploads\/icon-pallet-box.svg\" \/> 528 units<\/p>\n<p><img decoding=\"async\" class=\"prod-carac-icon\" src=\"\/wp-content\/uploads\/icon-prod-color-blanco.svg\" \/><img decoding=\"async\" class=\"prod-carac-icon\" src=\"\/wp-content\/uploads\/icon-prod-carac-alimentacion.svg\" \/><\/p>\n","protected":false},"featured_media":3927,"template":"","meta":[],"product_cat":[98,100],"product_tag":[],"_links":{"self":[{"href":"https:\/\/denox.eu\/en\/wp-json\/wp\/v2\/product\/3610"}],"collection":[{"href":"https:\/\/denox.eu\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/denox.eu\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/denox.eu\/en\/wp-json\/wp\/v2\/media\/3927"}],"wp:attachment":[{"href":"https:\/\/denox.eu\/en\/wp-json\/wp\/v2\/media?parent=3610"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/denox.eu\/en\/wp-json\/wp\/v2\/product_cat?post=3610"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/denox.eu\/en\/wp-json\/wp\/v2\/product_tag?post=3610"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}