{"id":3543,"date":"2020-12-14T09:16:58","date_gmt":"2020-12-14T08:16:58","guid":{"rendered":"https:\/\/denox.eu\/producto\/selectivo-120l\/"},"modified":"2022-11-30T11:56:23","modified_gmt":"2022-11-30T10:56:23","slug":"selectivo-120l","status":"publish","type":"product","link":"https:\/\/denox.eu\/en\/producto\/selectivo-120l\/","title":{"rendered":"Selectivo 120L."},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<ul>\n<li>Lidded container for the collection and classification of waste.<\/li>\n<li>Easy to move thanks to its two wheels and ergonomic handle.<\/li>\n<li>Hygienic, with a pedal to open the lid and easy to clean.<\/li>\n<li>The lids are available in different colours for waste management: white, green, blue, yellow, red, black or brown on a grey or white base, at your choice.<\/li>\n<li>Strong and durable.<\/li>\n<\/ul>\n<p class=\"prod-desc-resaltado\">Sizing (mm) : 510 x 425 x 875<\/p>\n<p class=\"prod-desc-unidades\"><img decoding=\"async\" class=\"prod-desc-icon\" role=\"img\" src=\"\/wp-content\/uploads\/icon-box-cont.svg\" \/> 1<\/p>\n<p class=\"prod-desc-unidades\"><img decoding=\"async\" class=\"prod-desc-icon\" role=\"img\" src=\"\/wp-content\/uploads\/icon-pallet-box.svg\" \/> 30 units<\/p>\n<p><img decoding=\"async\" class=\"prod-carac-icon\" src=\"\/wp-content\/uploads\/icon-prod-color-azul.svg\" \/><img decoding=\"async\" class=\"prod-carac-icon\" src=\"\/wp-content\/uploads\/icon-prod-color-verde.svg\" \/><img decoding=\"async\" class=\"prod-carac-icon\" src=\"\/wp-content\/uploads\/icon-prod-color-rojo.svg\" \/><img decoding=\"async\" class=\"prod-carac-icon\" src=\"\/wp-content\/uploads\/icon-prod-color-amarillo.svg\" \/><img decoding=\"async\" class=\"prod-carac-icon\" src=\"\/wp-content\/uploads\/icon-prod-color-negro.svg\" \/><img decoding=\"async\" class=\"prod-carac-icon\" src=\"\/wp-content\/uploads\/icon-prod-color-blanco.svg\" \/><img decoding=\"async\" class=\"prod-carac-icon\" src=\"\/wp-content\/uploads\/icon-prod-color-marron.svg\" \/><img decoding=\"async\" class=\"prod-carac-icon\" src=\"\/wp-content\/uploads\/icon-prod-cap-120.svg\" \/><img decoding=\"async\" class=\"prod-carac-icon\" src=\"\/wp-content\/uploads\/icon-prod-carac-encajable.svg\" \/><img decoding=\"async\" class=\"prod-carac-icon\" src=\"\/wp-content\/uploads\/icon-prod-sizing-23400.png\" \/><\/p>\n","protected":false},"featured_media":5260,"template":"","meta":[],"product_cat":[108,110],"product_tag":[],"_links":{"self":[{"href":"https:\/\/denox.eu\/en\/wp-json\/wp\/v2\/product\/3543"}],"collection":[{"href":"https:\/\/denox.eu\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/denox.eu\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/denox.eu\/en\/wp-json\/wp\/v2\/media\/5260"}],"wp:attachment":[{"href":"https:\/\/denox.eu\/en\/wp-json\/wp\/v2\/media?parent=3543"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/denox.eu\/en\/wp-json\/wp\/v2\/product_cat?post=3543"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/denox.eu\/en\/wp-json\/wp\/v2\/product_tag?post=3543"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}